{"id":55897,"date":"2026-05-12T08:17:03","date_gmt":"2026-05-12T11:17:03","guid":{"rendered":"https:\/\/clicdenoticias.com\/?p=55897"},"modified":"2026-05-12T08:17:05","modified_gmt":"2026-05-12T11:17:05","slug":"la-mama-de-bastian-jerez-lanzo-una-rifa-para-pagar-los-costos-de-la-internacion","status":"publish","type":"post","link":"https:\/\/clicdenoticias.com\/index.php\/2026\/05\/12\/la-mama-de-bastian-jerez-lanzo-una-rifa-para-pagar-los-costos-de-la-internacion\/","title":{"rendered":"La mam\u00e1 de Basti\u00e1n Jerez lanz\u00f3 una rifa para pagar los costos de la internaci\u00f3n"},"content":{"rendered":"\n<p>La madre de<strong>&nbsp;Basti\u00e1n Jerez<\/strong>&nbsp;lanz\u00f3 una&nbsp;<strong>rifa solidaria<\/strong>&nbsp;para pagar los&nbsp;<strong>costos de la internaci\u00f3n de su hijo<\/strong>, quien se recupera de las heridas sufridas por el choque entre un veh\u00edculo UTV y una camioneta Volkswagen Amarok en la ciudad balnearia de Pinamar.<\/p>\n\n\n\n<p>Seg\u00fan public\u00f3 Macarena Collantes en su cuenta de Instagram, cada n\u00famero tiene un costo de&nbsp;<strong>$10.000<\/strong>&nbsp;y se sortean cinco premios: un<strong>&nbsp;costillar<\/strong>, una&nbsp;<strong>pava el\u00e9ctrica<\/strong>, un&nbsp;<strong>termo<\/strong>&nbsp;y una<strong>&nbsp;freidora de aire.<\/strong><\/p>\n\n\n\n<p>La mujer se\u00f1al\u00f3 que se pueden comprar mediante el env\u00edo de una transferencia a su alias&nbsp;<strong>basti.maca<\/strong>, perteneciente al Banco Provincia.<\/p>\n\n\n\n<p>Adem\u00e1s,&nbsp;<strong>Basti\u00e1n est\u00e1 a punto de completar el equipo de la Selecci\u00f3n argentina con todas las figuritas en el \u00e1lbum del Mundial 2026.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madre de&nbsp;Basti\u00e1n Jerez&nbsp;lanz\u00f3 una&nbsp;rifa solidaria&nbsp;para pagar los&nbsp;costos de la internaci\u00f3n de su hijo, quien se recupera de las heridas sufridas por el choque entre un veh\u00edculo UTV y una camioneta Volkswagen Amarok en la ciudad balnearia de Pinamar. Seg\u00fan public\u00f3 Macarena Collantes en su cuenta de Instagram, cada n\u00famero tiene un costo de&nbsp;$10.000&nbsp;y se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":55898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-55897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad"],"_links":{"self":[{"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55897"}],"version-history":[{"count":1,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55897\/revisions"}],"predecessor-version":[{"id":55899,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55897\/revisions\/55899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55898"}],"wp:attachment":[{"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clicdenoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}